{"id":5386,"date":"2016-10-05T21:18:20","date_gmt":"2016-10-05T19:18:20","guid":{"rendered":"https:\/\/mirlett.com\/?post_type=product&#038;p=5386"},"modified":"2022-03-05T19:43:45","modified_gmt":"2022-03-05T18:43:45","slug":"marimekko-vestido-noppeesti","status":"publish","type":"product","link":"https:\/\/mirlett.com\/es\/marimekko-vestido-noppeesti\/","title":{"rendered":"MARIMEKKO vestido NOPPEESTI"},"content":{"rendered":"[vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbblack\u00bb text_align=\u00bbleft\u00bb overlay_strength=\u00bb0.3&#8243;][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb3&#8243; background_hover_color_opacity=\u00bb1&#8243; width=\u00bb1\/1&#8243; tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb][toggles style=\u00bbminimal_shadow\u00bb accordion=\u00bbtrue\u00bb][toggles accordion=\u00bbtrue\u00bb]\n[toggle title=\u00bbDESCRIPCION\u00bb color=\u00bbExtra-Color-2&#8243; id=\u00bbb1&#8243;]Vestido de Marimekko por encima de la rodilla de corte recto ligeramente mas cerrado por la parte de abajo. De cuello redondo, pinzas laterales en el pecho, mangas hasta el codo, bolsillos insertados laterales y cierre de cremallera invisible en la parte central trasera. De tejido suave pero con estructura. Forrado en negro.\u00a0El estampado de remolinos Hulahula est\u00e1 dise\u00f1ado por <strong>Reeta Ek<\/strong>.[\/toggle]\n[toggle title=\u00bbDETALLES\u00bb color=\u00bbExtra-Color-2&#8243; id=\u00bbb2&#8243;]- Color blanco y negro.<br \/>\n&#8211; <em>Exterior<\/em>:\u00a097% algod\u00f3n y 3% elastano;<br \/>\n&#8211; <em>Interior<\/em>:\u00a096% poli\u00e9ster y 4% elastano.<br \/>\n&#8211; Longitud: 95cm. (talla 38)<br \/>\n&#8211; Lavar por separado.<br \/>\n&#8211; Lavar en seco o lavar del rev\u00e9s a m\u00e1quina m\u00e1x. 30\u00baC.<br \/>\n&#8211; Planchar del rev\u00e9s a temperatura media.<br \/>\n&#8211; No usar secadora.<br \/>\n&#8211; No usar lej\u00eda.<br \/>\n&#8211; Hecho en Lituania.[\/toggle]\n[toggle title=\u00bbPRECIO y ENVIOS\u00bb color=\u00bbExtra-Color-2&#8243; id=\u00bbb3&#8243;]- Impuesto IVA incluido.<br \/>\n&#8211; <strong>Env\u00edo nacional<\/strong> (Pen\u00ednsula) <strong>gratuito<\/strong>.<br \/>\n&#8211; Env\u00edo internacional NO incluido.<br \/>\n&#8211; El coste del env\u00edo aparecer\u00e1 en la p\u00e1gina de pago.<br \/>\n&#8211; Ofrecemos env\u00edos gratuitos, consulta el pedido m\u00ednimo:<\/p>\n<table>\n<tbody>\n<tr>\n<td bgcolor=\"e8e3dc\">Localizaci\u00f3n<\/td>\n<td bgcolor=\"e8e3dc\">Entrega<\/td>\n<td bgcolor=\"e8e3dc\">Precio<\/td>\n<td bgcolor=\"e8e3dc\">M\u00ednimo<\/td>\n<\/tr>\n<tr>\n<td>Barcelona<\/td>\n<td>24h<\/td>\n<td>0\u20ac<\/td>\n<td>0\u20ac<\/td>\n<\/tr>\n<tr>\n<td>Espa\u00f1a<\/td>\n<td>1-2 d\u00edas<\/td>\n<td>0\u20ac<\/td>\n<td>0\u20ac<\/td>\n<\/tr>\n<tr>\n<td bgcolor=\"e8e3dc\">Europe<\/td>\n<td bgcolor=\"e8e3dc\"><\/td>\n<td bgcolor=\"e8e3dc\"><\/td>\n<td bgcolor=\"e8e3dc\"><\/td>\n<\/tr>\n<tr>\n<td>U.E.<\/td>\n<td>3-5 days<\/td>\n<td>15\u20ac<\/td>\n<td>250\u20ac<\/td>\n<\/tr>\n<tr>\n<td>non-U.E.<\/td>\n<td>3-5 days<\/td>\n<td>30\u20ac<\/td>\n<td>250\u20ac<\/td>\n<\/tr>\n<tr>\n<td bgcolor=\"e8e3dc\">North America<\/td>\n<td bgcolor=\"e8e3dc\"><\/td>\n<td bgcolor=\"e8e3dc\"><\/td>\n<td bgcolor=\"e8e3dc\"><\/td>\n<\/tr>\n<tr>\n<td>Canada<\/td>\n<td>5-7 days<\/td>\n<td>40\u20ac<\/td>\n<td>350\u20ac<\/td>\n<\/tr>\n<tr>\n<td>USA<\/td>\n<td>5-7 days<\/td>\n<td>40\u20ac<\/td>\n<td>350\u20ac<\/td>\n<\/tr>\n<tr>\n<td bgcolor=\"e8e3dc\">Worldwide<\/td>\n<td bgcolor=\"e8e3dc\"><\/td>\n<td bgcolor=\"e8e3dc\"><\/td>\n<td bgcolor=\"e8e3dc\"><\/td>\n<\/tr>\n<tr>\n<td>Worldwide<\/td>\n<td>5-7 days<\/td>\n<td>50\u20ac<\/td>\n<td>350\u20ac<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&#8211; <a href=\"https:\/\/mirlett.com\/tarifas-tiempos-envio-a-domicilio\/\">Consulta<\/a> los detalles.[\/toggle][\/toggles]\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbblack\u00bb text_align=\u00bbleft\u00bb overlay_strength=\u00bb0.3&#8243;][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb3&#8243; background_hover_color_opacity=\u00bb1&#8243; width=\u00bb1\/1&#8243; tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb][toggles style=\u00bbminimal_shadow\u00bb accordion=\u00bbtrue\u00bb][toggles accordion=\u00bbtrue\u00bb] [toggle title=\u00bbDESCRIPCION\u00bb color=\u00bbExtra-Color-2&#8243; id=\u00bbb1&#8243;]Vestido de Marimekko por encima de la rodilla de corte&#8230;<\/p>\n","protected":false},"featured_media":5388,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[69,403,182,79],"product_tag":[1457,1870,1496,126,125,168,169,127,195,1728,1615,331,1363,416,344,1708,1612],"class_list":["post-5386","product","type-product","status-publish","has-post-thumbnail","product_cat-marimekko-ropa-barcelona","product_cat-marcas","product_cat-mujer","product_cat-vestidos","product_tag-boutique-barcelona","product_tag-comercio-barcelona","product_tag-compras-barcelona","product_tag-estilo-escandinavo","product_tag-estilo-nordico-barcelona","product_tag-marimekko-barcelona","product_tag-marimekko-espana-mirlett","product_tag-ropa-estilo-nordico","product_tag-ropa-marimekko","product_tag-ropa-mujer-barcelona","product_tag-tienda-marimekko","product_tag-tienda-mirlett","product_tag-tienda-multimarca","product_tag-tienda-ropa-barcelona","product_tag-tienda-ropa-marimekko","product_tag-tienda-ropa-el-born-barcelona-mirlett","product_tag-vestido-marimekko","product_shipping_class-envio-normal","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/mirlett.com\/es\/wp-json\/wp\/v2\/product\/5386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mirlett.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mirlett.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/mirlett.com\/es\/wp-json\/wp\/v2\/comments?post=5386"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mirlett.com\/es\/wp-json\/wp\/v2\/media\/5388"}],"wp:attachment":[{"href":"https:\/\/mirlett.com\/es\/wp-json\/wp\/v2\/media?parent=5386"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mirlett.com\/es\/wp-json\/wp\/v2\/product_brand?post=5386"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mirlett.com\/es\/wp-json\/wp\/v2\/product_cat?post=5386"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mirlett.com\/es\/wp-json\/wp\/v2\/product_tag?post=5386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}