{"id":69893,"date":"2026-04-01T19:00:42","date_gmt":"2026-04-01T17:00:42","guid":{"rendered":"https:\/\/mirlett.com\/?post_type=product&#038;p=69893"},"modified":"2026-04-02T18:53:25","modified_gmt":"2026-04-02T16:53:25","slug":"twothirds-barcelona-sudadera-niza-rosa","status":"publish","type":"product","link":"https:\/\/mirlett.com\/es\/twothirds-barcelona-sudadera-niza-rosa\/","title":{"rendered":"TWOTHIRDS sudadera NIZA"},"content":{"rendered":"[vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbblack\u00bb text_align=\u00bbleft\u00bb overlay_strength=\u00bb0.3&#8243;][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb3&#8243; background_hover_color_opacity=\u00bb1&#8243; width=\u00bb1\/1&#8243; tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb][toggles style=\u00bbminimal_shadow\u00bb accordion=\u00bbtrue\u00bb][toggles accordion=\u00bbtrue\u00bb]\n[toggle title=\u00bbDESCRIPCION\u00bb color=\u00bbExtra-Color-2&#8243; id=\u00bbb1&#8243;]Sudadera Niza de TwoThirds de felpa americana muy suave de corte relajado, hombros ca\u00eddos y logotipo bordado. Hecho en Portugal.[\/toggle]\n[toggle title=\u00bbDETALLES\u00bb color=\u00bbExtra-Color-2&#8243; id=\u00bbb2&#8243;]- 100% algod\u00f3n org\u00e1nico.<br \/>\n&#8211; Sin pesticidas.<br \/>\n&#8211; Consumo de agua reducido.<br \/>\n&#8211; Vegano.<br \/>\n&#8211; Dise\u00f1ado en Barcelona.<br \/>\n&#8211; Fabricado en Portugal.[\/toggle]\n[toggle title=\u00bbPRECIO y ENVIOS\u00bb color=\u00bbExtra-Color-2&#8243; id=\u00bbb3&#8243;]- Impuesto IVA incluido.<br \/>\n&#8211; <strong>Env\u00edo nacional<\/strong> (Pen\u00ednsula) <strong>gratuito<\/strong>.<br \/>\n&#8211; Env\u00edo internacional NO incluido.<br \/>\n&#8211; El coste del env\u00edo aparecer\u00e1 en la p\u00e1gina de pago.<br \/>\n&#8211; Ofrecemos env\u00edos gratuitos, consulta el pedido m\u00ednimo:<\/p>\n<table>\n<tbody>\n<tr>\n<td bgcolor=\"e8e3dc\"><\/td>\n<td bgcolor=\"e8e3dc\">Entrega<\/td>\n<td bgcolor=\"e8e3dc\">Precio<\/td>\n<td bgcolor=\"e8e3dc\">M\u00ednimo<\/td>\n<\/tr>\n<tr>\n<td>Barcelona<\/td>\n<td>24h<\/td>\n<td>0\u20ac<\/td>\n<td>0\u20ac<\/td>\n<\/tr>\n<tr>\n<td>Espa\u00f1a<\/td>\n<td>1-2 d\u00edas<\/td>\n<td>0\u20ac<\/td>\n<td>0\u20ac<\/td>\n<\/tr>\n<tr>\n<td bgcolor=\"e8e3dc\">Europe<\/td>\n<td bgcolor=\"e8e3dc\"><\/td>\n<td bgcolor=\"e8e3dc\"><\/td>\n<td bgcolor=\"e8e3dc\"><\/td>\n<\/tr>\n<tr>\n<td>U.E.<\/td>\n<td>3-5 days<\/td>\n<td>15\u20ac<\/td>\n<td>250\u20ac<\/td>\n<\/tr>\n<tr>\n<td>non-U.E.<\/td>\n<td>3-5 days<\/td>\n<td>30\u20ac<\/td>\n<td>250\u20ac<\/td>\n<\/tr>\n<tr>\n<td bgcolor=\"e8e3dc\">N. America<\/td>\n<td bgcolor=\"e8e3dc\"><\/td>\n<td bgcolor=\"e8e3dc\"><\/td>\n<td bgcolor=\"e8e3dc\"><\/td>\n<\/tr>\n<tr>\n<td>Canada<\/td>\n<td>5-7 days<\/td>\n<td>40\u20ac<\/td>\n<td>350\u20ac<\/td>\n<\/tr>\n<tr>\n<td>USA<\/td>\n<td>5-7 days<\/td>\n<td>40\u20ac<\/td>\n<td>350\u20ac<\/td>\n<\/tr>\n<tr>\n<td bgcolor=\"e8e3dc\">Worldwide<\/td>\n<td bgcolor=\"e8e3dc\"><\/td>\n<td bgcolor=\"e8e3dc\"><\/td>\n<td bgcolor=\"e8e3dc\"><\/td>\n<\/tr>\n<tr>\n<td>Worldwide<\/td>\n<td>5-7 days<\/td>\n<td>50\u20ac<\/td>\n<td>350\u20ac<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&#8211; <a href=\"https:\/\/mirlett.com\/es\/tarifas-tiempos-envio-a-domicilio\/\">Consulta<\/a> los detalles.[\/toggle]\n[toggle title=\u00bbMEDIDAS (cm) y TALLAS\u00bb color=\u00bbExtra-Color-2&#8243; id=\u00bbb1&#8243;]\n<table>\n<tbody>\n<tr>\n<td bgcolor=\"e8e3dc\">EU<\/td>\n<td bgcolor=\"e8e3dc\">Hombros<\/td>\n<td bgcolor=\"e8e3dc\">Pecho<\/td>\n<td bgcolor=\"e8e3dc\">Largo<\/td>\n<td bgcolor=\"e8e3dc\">Mangas<\/td>\n<\/tr>\n<tr>\n<td>S<\/td>\n<td>68,5<\/td>\n<td>63,5<\/td>\n<td>60<\/td>\n<td>44,5<\/td>\n<\/tr>\n<tr>\n<td>M<\/td>\n<td>69,5<\/td>\n<td>65,5<\/td>\n<td>62<\/td>\n<td>45,3<\/td>\n<\/tr>\n<tr>\n<td>L<\/td>\n<td>70,5<\/td>\n<td>67,5<\/td>\n<td>64<\/td>\n<td>46,1<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div id=\"attachment_69894\" style=\"width: 810px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-69894\" class=\"size-full wp-image-69894\" src=\"https:\/\/mirlett.com\/wp-content\/smush-webp\/2026\/04\/Knits_Sweats.jpg.webp\" alt=\"twothirds sweater knitwear measures\" width=\"800\" height=\"434\" srcset=\"https:\/\/mirlett.com\/wp-content\/smush-webp\/2026\/04\/Knits_Sweats.jpg.webp 800w, https:\/\/mirlett.com\/wp-content\/smush-webp\/2026\/04\/Knits_Sweats-300x163.jpg.webp 300w, https:\/\/mirlett.com\/wp-content\/uploads\/2026\/04\/Knits_Sweats-650x353.jpg 650w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><p id=\"caption-attachment-69894\" class=\"wp-caption-text\">twothirds sweater knitwear measures<\/p><\/div>\n<p>&#8211; <strong>Cintura <sup>(A)<\/sup><\/strong> &#8211; Medir en la parte m\u00e1s estrecha de la cintura.<br \/>\n&#8211; <strong>Cadera <sup>(B)<\/sup><\/strong> &#8211; Medir en la parte m\u00e1s ancha de la cadera.<br \/>\n&#8211; <strong>Longitud total <sup>(C)<\/sup><\/strong> &#8211; Medir\u00a0desde la parte superior de la pretina hasta el bajo de la prenda.<br \/>\n&#8211; <strong>Manga <sup>D<\/sup><\/strong> &#8211; Medir desde la costura de la sisa hasta el extremo del pu\u00f1o.<\/p>\n<table>\n<tbody>\n<tr>\n<td bgcolor=\"e8e3dc\">EU<\/td>\n<td bgcolor=\"e8e3dc\">Pecho<\/td>\n<td bgcolor=\"e8e3dc\">Cintura<\/td>\n<td bgcolor=\"e8e3dc\">Cadera<\/td>\n<\/tr>\n<tr>\n<td>S<\/td>\n<td>84-88<\/td>\n<td>68-72<\/td>\n<td>n\/a<\/td>\n<\/tr>\n<tr>\n<td>M<\/td>\n<td>88-92<\/td>\n<td>72-76<\/td>\n<td>n\/a<\/td>\n<\/tr>\n<tr>\n<td>L<\/td>\n<td>92-96<\/td>\n<td>76-80<\/td>\n<td>n\/a<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-69807 size-full\" src=\"https:\/\/mirlett.com\/wp-content\/smush-webp\/2026\/03\/WOMEN_237d7a37-bd7b-45c3-9032-5d507e2ce93c-1.png.webp\" alt=\"TWOTHIRDS | BODY MEASURES\" width=\"800\" height=\"433\" srcset=\"https:\/\/mirlett.com\/wp-content\/smush-webp\/2026\/03\/WOMEN_237d7a37-bd7b-45c3-9032-5d507e2ce93c-1.png.webp 800w, https:\/\/mirlett.com\/wp-content\/smush-webp\/2026\/03\/WOMEN_237d7a37-bd7b-45c3-9032-5d507e2ce93c-1-300x162.png.webp 300w, https:\/\/mirlett.com\/wp-content\/uploads\/2026\/03\/WOMEN_237d7a37-bd7b-45c3-9032-5d507e2ce93c-1-650x352.png 650w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>&#8211; <strong>Pecho\u00a0<sup>(1)<\/sup><\/strong> &#8211; Mida el contorno de su pecho en la parte m\u00e1s ancha, con la cinta m\u00e9trica debajo de los brazos y los brazos relajados a los lados.<br \/>\n&#8211; <strong>Cintura\u00a0<sup>(2)<\/sup><\/strong> &#8211; Mida el contorno de su cintura en la parte m\u00e1s estrecha.<br \/>\n&#8211; <strong>Cadera \u00a0<sup>(3)<\/sup><\/strong> &#8211; P\u00f3ngase de pie con los pies separados al ancho de las caderas y mida el contorno de sus caderas en la parte m\u00e1s ancha.[\/toggle] [\/toggles]\n","protected":false},"excerpt":{"rendered":"<p>[button color=\"see-through\" hover_text_color_override=\"#000\" size=\"medium\" url=\"\" text=\"NOVEDAD\" color_override=\"#000000\"]<br \/>\n[icon color=\"extra-color-2\" size=\"tiny\" icon_size=\"\" image=\"fa-shopping-basket\"] Disponible tambi\u00e9n en nuestra tienda f\u00edsica en El Born de Barcelona.<br \/>\n[icon color=\"extra-color-2\" size=\"tiny\" icon_size=\"\" image=\"fa-truck\"] Env\u00edos nacionales gratis en 24h-48h.<br \/>\n[icon color=\"extra-color-2\" size=\"tiny\" icon_size=\"\" image=\"fa-credit-card\"] Pago 100% seguro con tarjeta.<br \/>\n[icon color=\"extra-color-2\" size=\"tiny\" icon_size=\"\" image=\"fa-smile-o\"] Paypal: opci\u00f3n pago fraccionado sin intereses.<\/p>\n","protected":false},"featured_media":69897,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[55,403,182,2527],"product_tag":[1457,1727,1870,1496,1728,2551,331,1363,416,1708,2542,2530,2531],"class_list":["post-69893","product","type-product","status-publish","has-post-thumbnail","product_cat-jerseis-mujer","product_cat-marcas","product_cat-mujer","product_cat-twothirds-barcelona","product_tag-boutique-barcelona","product_tag-boutique-multimarca-2","product_tag-comercio-barcelona","product_tag-compras-barcelona","product_tag-ropa-mujer-barcelona","product_tag-sudadera-twothirds","product_tag-tienda-mirlett","product_tag-tienda-multimarca","product_tag-tienda-ropa-barcelona","product_tag-tienda-ropa-el-born-barcelona-mirlett","product_tag-two-thirds","product_tag-twothirds-barcelona","product_tag-twothirds-espana","product_shipping_class-envio-normal-ca","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/mirlett.com\/es\/wp-json\/wp\/v2\/product\/69893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mirlett.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mirlett.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/mirlett.com\/es\/wp-json\/wp\/v2\/comments?post=69893"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mirlett.com\/es\/wp-json\/wp\/v2\/media\/69897"}],"wp:attachment":[{"href":"https:\/\/mirlett.com\/es\/wp-json\/wp\/v2\/media?parent=69893"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mirlett.com\/es\/wp-json\/wp\/v2\/product_brand?post=69893"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mirlett.com\/es\/wp-json\/wp\/v2\/product_cat?post=69893"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mirlett.com\/es\/wp-json\/wp\/v2\/product_tag?post=69893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}